{"id":2539,"date":"2023-08-23T23:00:00","date_gmt":"2023-08-24T02:00:00","guid":{"rendered":"https:\/\/fungiteka.xyz\/?p=2539"},"modified":"2023-10-11T20:33:37","modified_gmt":"2023-10-11T23:33:37","slug":"los-registros-mas-antiguos-de-consumo-de-hongos-en-america","status":"publish","type":"post","link":"https:\/\/fungiteka.xyz\/index.php\/2023\/08\/23\/los-registros-mas-antiguos-de-consumo-de-hongos-en-america\/","title":{"rendered":"El consumo de hongos en Am\u00e9rica precolombina (primera parte)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Los primeros registros de consumo de hongos en Am\u00e9rica pertenecen a la Cultura Capacha y son unas estatuillas de cer\u00e1mica donde se representan seres humanos en relaci\u00f3n con hongos. \u00c9stas pueden interpretarse como ritos, o bien, como percepciones alteradas por el consumo de setas nuerotr\u00f3picas o alucin\u00f3genas<sup data-fn=\"84deadfc-b2dc-4246-b16a-ced918fa628a\" class=\"fn\"><a href=\"#84deadfc-b2dc-4246-b16a-ced918fa628a\" id=\"84deadfc-b2dc-4246-b16a-ced918fa628a-link\">1<\/a><\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Capacha es un sitio arqueol\u00f3gico ubicado a unos 6 kil\u00f3metros al noreste del municipio de Colima, en el Estado de Colima, M\u00e9xico. Este sitio es el coraz\u00f3n de la antigua Cultura Capacha mesoamericana, la primera con rasgos complejos que se desarroll\u00f3 en la regi\u00f3n, aproximadamente entre los a\u00f1os 2.000 y 1.200&nbsp; antes de nuestra era.&nbsp; Estos pueblos se asentaron entre la Sierra Madre Occidental de Jalisco y el Valle de Colima.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/07\/mapa-Mexico-capacha.png\" alt=\"Cultura Capacha mapa\" class=\"wp-image-2248\" style=\"width:471px;height:336px\" width=\"471\" height=\"336\" srcset=\"https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/07\/mapa-Mexico-capacha.png 600w, https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/07\/mapa-Mexico-capacha-300x214.png 300w\" sizes=\"auto, (max-width: 471px) 100vw, 471px\" \/><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Estas estatuillas de cer\u00e1mica fueron estudiadas por Gast\u00f3n Guzm\u00e1n del Instituto de Ecolog\u00eda de Veracruz, M\u00e9xico y lo que vamos a describir se basa en su trabajo: \u201c<em>El uso tradicional de los hongos sagrados: pasado y presente\u201d<\/em><sup data-fn=\"730b55d0-4524-4ac4-83ad-eca8dd0b343b\" class=\"fn\"><a href=\"#730b55d0-4524-4ac4-83ad-eca8dd0b343b\" id=\"730b55d0-4524-4ac4-83ad-eca8dd0b343b-link\">2<\/a><\/sup><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">En una de las estatuillas encontradas se representa cuatro personas abrazadas entre s\u00ed para guardar el equilibrio y a su vez rodeando a un hongo gigante que bien podr\u00eda identificarse con Psilocybe zapotecorum. Guzm\u00e1n destaca los ojos desorbitados de todos los personajes al ver el hongo gigante y los sombreros y brazos, que representan serpientes. Si bien hay algunos autores que consideran que la figurilla representa un baile, Guzm\u00e1n interpret\u00f3 que las personas de la figura est\u00e1n bajo el efecto de hongos neurotr\u00f3picos y que por lo tanto, no pueden estar paradas y menos guardar el equilibrio.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/07\/estatuilla-capacha-1-e1692649150958.png\" alt=\"\" class=\"wp-image-2250\" style=\"width:364px;height:372px\" width=\"364\" height=\"372\" srcset=\"https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/07\/estatuilla-capacha-1-e1692649150958.png 452w, https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/07\/estatuilla-capacha-1-e1692649150958-294x300.png 294w\" sizes=\"auto, (max-width: 364px) 100vw, 364px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:38px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En otras dos estatuillas encontramos la imagen de una mujer en relaci\u00f3n con un hongo, donde los tama\u00f1os est\u00e1n distorsionados, probablemente para representar la sensaci\u00f3n del enanismo o gigantismo que estos hongos producen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la primera, que se encuentra en el Museo Alejandro Rangel en Nogueras, Colima,&nbsp; se observa una mujer con los ojos desorbitados que est\u00e1 de pie con un hongo gigante en su mano derecha. Se la conoce como \u201cmujer con sombrilla\u201d y al hongo se lo identifica como Psilocybe zapotecorum<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la segunda podemos ver&nbsp; una mujer recostada debajo de un hongo gigante. Pertenece al Museo del R\u00edo Cuale, en Puerto Vallarta. Seg\u00fan Guzm\u00e1n esta estatuilla representa&nbsp; la necesidad de reposar por la acci\u00f3n neurotr\u00f3pica de estos hongos y considera que el hongo pertenece a una especie de Psilocybe desconocida.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"322\" height=\"600\" src=\"https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/07\/estatuilla-capacha-2.png\" alt=\"\" class=\"wp-image-2252\" srcset=\"https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/07\/estatuilla-capacha-2.png 322w, https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/07\/estatuilla-capacha-2-161x300.png 161w\" sizes=\"auto, (max-width: 322px) 100vw, 322px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"418\" src=\"https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/07\/estatuilla-capacha-3.png\" alt=\"\" class=\"wp-image-2253\" srcset=\"https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/07\/estatuilla-capacha-3.png 600w, https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/07\/estatuilla-capacha-3-300x209.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:46px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de estas estatuillas, hay una cuarta, muy conocida y de la que hay controversia sobre la representaci\u00f3n de hongos en la misma. Se trata del famoso Xochipilli o Se\u00f1or de las Flores, el que seg\u00fan Wasson (otro especialista en el tema, al que dedicaremos alguna referencia m\u00e1s adelante), adem\u00e1s de tener flores grabadas tiene hongos neurotr\u00f3picos, como P. aztecorum. No todos los especialistas coinciden en esta apreciaci\u00f3n, pero como se trata de la representaci\u00f3n del dios tutelar de las flores, la fertilidad, la nobleza, la poes\u00eda y el canto entre los mexicas,&nbsp; no quise dejar de mencionarla y recomendar leer m\u00e1s sobre ella<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image alignright size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"393\" height=\"396\" src=\"https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/08\/xochipilli.jpg\" alt=\"\" class=\"wp-image-2528\" srcset=\"https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/08\/xochipilli.jpg 393w, https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/08\/xochipilli-298x300.jpg 298w, https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/08\/xochipilli-150x150.jpg 150w\" sizes=\"auto, (max-width: 393px) 100vw, 393px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:34px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Xochipilli, el Se\u00f1or de las Flores<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mediateca INAH, Instituto Nacional de Antropolog\u00eda e Histor\u00eda, M\u00e9xico<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">http:\/\/mediateca.inah.gob.mx\/repositorio\/islandora\/object\/exposicion%3A3141<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:39px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Las im\u00e1genes de las estatuillas, salvo esta \u00faltima, fueron extra\u00eddas del art\u00edculo de G.Guzm\u00e1n citado<\/p>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<ol class=\"wp-block-footnotes\"><li id=\"84deadfc-b2dc-4246-b16a-ced918fa628a\">Muchos autores prefieren el adjetivo de enteog\u00e9nico para hacer referencia a estas setas, en cambio G. Guzm\u00e1n, al que hacemos referencia en este texto, no lo considera adecuado porque proviene del griego entheos= dios dentro y esto implicar\u00eda que la acci\u00f3n de estos hongos est\u00e1 ligada con un dios que entra en el cuerpo al ingerir la seta. Como considera que la ciencia debe ser ajena a cualquier religi\u00f3n, este autor prefiere las denominaciones neurotr\u00f3picos, alucin\u00f3genos o sagrados, seg\u00fan el caso. La denominaci\u00f3n de neuror\u00f3picos le parece la m\u00e1s apropiada, porque alude a algo que en nuestro organismo se mueve (de tropos, movimiento) hacia el sistema nervioso central, haciendo referencia a la psilocibina, el alcaloide que provoca efectos alucin\u00f3genos en estos hongos.. <a href=\"#84deadfc-b2dc-4246-b16a-ced918fa628a-link\" aria-label=\"Saltar a la referencia de la nota 1\">\u21a9\ufe0e<\/a><\/li><li id=\"730b55d0-4524-4ac4-83ad-eca8dd0b343b\">Guzm\u00e1n, G. \u201c<em>El uso tradicional de los hongos sagrados: pasado y presente\u201d<\/em>.  Instituto de Ecolog\u00eda, Veracruz, M\u00e9xico (2010). <a href=\"#730b55d0-4524-4ac4-83ad-eca8dd0b343b-link\" aria-label=\"Saltar a la referencia de la nota 2\">\u21a9\ufe0e<\/a><\/li><\/ol>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_2539\" class=\"pvc_stats all  \" data-element-id=\"2539\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/fungiteka.xyz\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Los primeros registros de consumo de hongos en Am\u00e9rica pertenecen a la Cultura Capacha y son unas estatuillas de cer\u00e1mica donde se representan seres humanos en relaci\u00f3n con hongos. \u00c9stas pueden interpretarse como ritos, o bien, como percepciones alteradas por el consumo de setas nuerotr\u00f3picas o alucin\u00f3genas. Capacha es un sitio arqueol\u00f3gico ubicado a unos [&hellip;]<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_2539\" class=\"pvc_stats all  \" data-element-id=\"2539\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/fungiteka.xyz\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":2250,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"_kadence_starter_templates_imported_post":false,"footnotes":"[{\"content\":\"Muchos autores prefieren el adjetivo de enteog\u00e9nico para hacer referencia a estas setas, en cambio G. Guzm\u00e1n, al que hacemos referencia en este texto, no lo considera adecuado porque proviene del griego entheos= dios dentro y esto implicar\u00eda que la acci\u00f3n de estos hongos est\u00e1 ligada con un dios que entra en el cuerpo al ingerir la seta. Como considera que la ciencia debe ser ajena a cualquier religi\u00f3n, este autor prefiere las denominaciones neurotr\u00f3picos, alucin\u00f3genos o sagrados, seg\u00fan el caso. La denominaci\u00f3n de neuror\u00f3picos le parece la m\u00e1s apropiada, porque alude a algo que en nuestro organismo se mueve (de tropos, movimiento) hacia el sistema nervioso central, haciendo referencia a la psilocibina, el alcaloide que provoca efectos alucin\u00f3genos en estos hongos..\",\"id\":\"84deadfc-b2dc-4246-b16a-ced918fa628a\"},{\"content\":\"Guzm\u00e1n, G. \u201c<em>El uso tradicional de los hongos sagrados: pasado y presente\u201d<\/em>.  Instituto de Ecolog\u00eda, Veracruz, M\u00e9xico (2010).\",\"id\":\"730b55d0-4524-4ac4-83ad-eca8dd0b343b\"}]"},"categories":[1],"tags":[],"class_list":["post-2539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia"],"a3_pvc":{"activated":true,"total_views":99,"today_views":0},"uagb_featured_image_src":{"full":["https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/07\/estatuilla-capacha-1-e1692649150958.png",452,462,false],"thumbnail":["https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/07\/estatuilla-capacha-1-e1692649150958-150x150.png",150,150,true],"medium":["https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/07\/estatuilla-capacha-1-e1692649150958-294x300.png",294,300,true],"medium_large":["https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/07\/estatuilla-capacha-1-e1692649150958.png",452,462,false],"large":["https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/07\/estatuilla-capacha-1-e1692649150958.png",452,462,false],"1536x1536":["https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/07\/estatuilla-capacha-1-e1692649150958.png",452,462,false],"2048x2048":["https:\/\/fungiteka.xyz\/wp-content\/uploads\/2023\/07\/estatuilla-capacha-1-e1692649150958.png",452,462,false]},"uagb_author_info":{"display_name":"Anakaona","author_link":"https:\/\/fungiteka.xyz\/author\/gabrielatubio\/"},"uagb_comment_info":38,"uagb_excerpt":"Los primeros registros de consumo de hongos en Am\u00e9rica pertenecen a la Cultura Capacha y son unas estatuillas de cer\u00e1mica donde se representan seres humanos en relaci\u00f3n con hongos. \u00c9stas pueden interpretarse como ritos, o bien, como percepciones alteradas por el consumo de setas nuerotr\u00f3picas o alucin\u00f3genas. Capacha es un sitio arqueol\u00f3gico ubicado a unos&hellip;","_links":{"self":[{"href":"https:\/\/fungiteka.xyz\/index.php\/wp-json\/wp\/v2\/posts\/2539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fungiteka.xyz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fungiteka.xyz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fungiteka.xyz\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fungiteka.xyz\/index.php\/wp-json\/wp\/v2\/comments?post=2539"}],"version-history":[{"count":17,"href":"https:\/\/fungiteka.xyz\/index.php\/wp-json\/wp\/v2\/posts\/2539\/revisions"}],"predecessor-version":[{"id":2576,"href":"https:\/\/fungiteka.xyz\/index.php\/wp-json\/wp\/v2\/posts\/2539\/revisions\/2576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fungiteka.xyz\/index.php\/wp-json\/wp\/v2\/media\/2250"}],"wp:attachment":[{"href":"https:\/\/fungiteka.xyz\/index.php\/wp-json\/wp\/v2\/media?parent=2539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fungiteka.xyz\/index.php\/wp-json\/wp\/v2\/categories?post=2539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fungiteka.xyz\/index.php\/wp-json\/wp\/v2\/tags?post=2539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}